{"id":4293,"date":"2018-06-14T10:16:59","date_gmt":"2018-06-14T14:16:59","guid":{"rendered":"https:\/\/naturegalapagos.com\/es\/?page_id=4293"},"modified":"2025-11-17T17:08:52","modified_gmt":"2025-11-17T22:08:52","slug":"trek-ecuador","status":"publish","type":"page","link":"https:\/\/naturegalapagos.com\/es\/trek-ecuador\/","title":{"rendered":"Trek Ecuador"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<h2><span style=\"font-family: arial, helvetica, sans-serif;\">Explore las maravillas andinas: Emb\u00e1rquese en inolvidables aventuras de trekking con Trek Ecuador Tours<\/span><\/h2>\n<hr \/>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>Trek Ecuador<\/strong> es una de nuestras secciones mas completas, no solo por los paisajes que visitamos, sino tambi\u00e9n porque nuestros itinerarios que est\u00e1n bien aprovechados en tiempo. Nuestros tours de Senderismo en Ecuador pueden ser de 1 a 4 d\u00edas, visitando los lugares mas hermosos del pa\u00eds aprovechando los caminos naturales y la vida silvestre de los Andes, pasando desde aldeas ind\u00edgenas, mestizas y varios poblados de campesinos que adornan la visi\u00f3n de los paramos andinos.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Despu\u00e9s de una conexi\u00f3n ancestral por los antiguos caminos incaicos seguiremos nuestra ruta observando las majestuosas monta\u00f1as que adornan la Cordillera de los Andes.<\/span>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column]<div id=\"swiper1\" class=\"atgrid\">\n<div class=\"title title--big title--center title--underline title--decoration-bottom-center\">\n\t<div class=\"title__subtitle\">Ecuador Tours<\/div>\n<h3 class=\"title__primary\">Senderismo en Ecuador<\/h3><\/div>\n\t<div class=\"atgrid__slider\">\n\t\t<div class=\"atgrid__slider__controls\">\n\t\t\t<a class=\"atgrid__slider__prev\" href=\"#\"><i class=\"fa fa-chevron-left\"><\/i><\/a>\n\t\t\t<a class=\"atgrid__slider__next\" href=\"#\"><i class=\"fa fa-chevron-right\"><\/i><\/a>\n\t\t<\/div>\n\n\t\t<div class=\"swiper-container swiper-slider atgrid__slider__container\">\n\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t<div class=\"atgrid__item\">\n\t\t\t\t\t\t<div class=\"atgrid__item__top\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/naturegalapagos.com\/es\/trek-ecuador\/trekking-altar-laguna-amarilla\/\" class=\"atgrid__item__top__image\"><img decoding=\"async\" width=\"360\" height=\"240\" src=\"https:\/\/naturegalapagos.com\/es\/wp-content\/uploads\/sites\/3\/2018\/06\/Trekking-Altar-360x240.jpg\" class=\"attachment-thumb_tour_listing_small size-thumb_tour_listing_small wp-post-image\" alt=\"Trekking Altar\" srcset=\"https:\/\/naturegalapagos.com\/es\/wp-content\/uploads\/sites\/3\/2018\/06\/Trekking-Altar-360x240.jpg 360w, https:\/\/naturegalapagos.com\/es\/wp-content\/uploads\/sites\/3\/2018\/06\/Trekking-Altar-531x354.jpg 531w, https:\/\/naturegalapagos.com\/es\/wp-content\/uploads\/sites\/3\/2018\/06\/Trekking-Altar-180x120.jpg 180w, https:\/\/naturegalapagos.com\/es\/wp-content\/uploads\/sites\/3\/2018\/06\/Trekking-Altar-270x180.jpg 270w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"atgrid__item__content\">\n\t\t\t\t\t\t\t<h3 class=\"atgrid__item__title\"><a href=\"https:\/\/naturegalapagos.com\/es\/trek-ecuador\/trekking-altar-laguna-amarilla\/\">Trekking Altar - Laguna Amarilla | Tour de Senderismo<\/a><\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"atgrid__item__description\">Trekking Altar - Laguna Amarilla es un tour de senderismo en Ecuador, con duraci\u00f3n de 3 d\u00edas! Visitando uno de los puntos mas hermosos y altos del pa\u00eds.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"item-attributes\">\n\t\t\t\t\t\t\t<div class=\"item-attributes__item\"><div class=\"item-attributes__item__content\"><div class=\"item-attributes__item__content__item\"><i class=\"td-clock-2\"><\/i><\/div><div class=\"item-attributes__item__content__item item-attributes__item__content__item--text\"><span>3 D\u00edas<\/span><\/div><\/div><\/div><div class=\"item-attributes__item\"><div class=\"item-attributes__item__content\"><div class=\"item-attributes__item__content__item\"><i class=\"td-backpack\"><\/i><\/div><div class=\"item-attributes__item__content__item item-attributes__item__content__item--text\"><span>Trekking Ecuador<\/span><\/div><\/div><\/div>\t\t\t\t\t\t\t<div class=\"item-attributes__item\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/naturegalapagos.com\/es\/trek-ecuador\/trekking-altar-laguna-amarilla\/\" class=\"item-attributes__link\"><i class=\"fa fa-long-arrow-right\"><\/i><\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t<div class=\"atgrid__item\">\n\t\t\t\t\t\t<div class=\"atgrid__item__top\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/naturegalapagos.com\/es\/cuenca-ecuador\/cuenca-tours\/cuenca-aventura\/\" class=\"atgrid__item__top__image\"><img decoding=\"async\" width=\"360\" height=\"240\" src=\"https:\/\/naturegalapagos.com\/es\/wp-content\/uploads\/sites\/3\/2015\/11\/cuenca-aventura-360x240.jpg\" class=\"attachment-thumb_tour_listing_small size-thumb_tour_listing_small wp-post-image\" alt=\"Parque Nacional El Cajas Senderismo\" srcset=\"https:\/\/naturegalapagos.com\/es\/wp-content\/uploads\/sites\/3\/2015\/11\/cuenca-aventura-360x240.jpg 360w, https:\/\/naturegalapagos.com\/es\/wp-content\/uploads\/sites\/3\/2015\/11\/cuenca-aventura-531x354.jpg 531w, https:\/\/naturegalapagos.com\/es\/wp-content\/uploads\/sites\/3\/2015\/11\/cuenca-aventura-270x180.jpg 270w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"atgrid__item__icons\"><a href=\"https:\/\/naturegalapagos.com\/es\/tour-category\/tours-de-cuenca\/\"><i data-toggle=\"tooltip\" title=\"Tours de Cuenca\" class=\"td-building-2\"><\/i><\/a><\/div>\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"atgrid__item__content\">\n\t\t\t\t\t\t\t<h3 class=\"atgrid__item__title\"><a href=\"https:\/\/naturegalapagos.com\/es\/cuenca-ecuador\/cuenca-tours\/cuenca-aventura\/\">Parque Nacional El Cajas Senderismo<\/a><\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"atgrid__item__description\">Cuenca aventura en la ciudad de Cuenca: Incluyen caminatas de exploraci\u00f3n en el Parque Nacional Cajas, pesca y observaci\u00f3n de aves. Clic Aqu\u00ed!! NG&amp;E<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"item-attributes\">\n\t\t\t\t\t\t\t<div class=\"item-attributes__item\"><div class=\"item-attributes__item__content\"><div class=\"item-attributes__item__content__item\"><i class=\"td-backpack\"><\/i><\/div><div class=\"item-attributes__item__content__item item-attributes__item__content__item--text\"><span>Aventura Sencilla<\/span><\/div><\/div><\/div><div class=\"item-attributes__item\"><div class=\"item-attributes__item__content\"><div class=\"item-attributes__item__content__item\"><i class=\"td-calendar-1\"><\/i><\/div><div class=\"item-attributes__item__content__item item-attributes__item__content__item--text\"><span>Todos los D\u00edas<\/span><\/div><\/div><\/div>\t\t\t\t\t\t\t<div class=\"item-attributes__item\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/naturegalapagos.com\/es\/cuenca-ecuador\/cuenca-tours\/cuenca-aventura\/\" class=\"item-attributes__link\"><i class=\"fa fa-long-arrow-right\"><\/i><\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t<div class=\"atgrid__item\">\n\t\t\t\t\t\t<div class=\"atgrid__item__top\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/naturegalapagos.com\/es\/tours-en-galapagos\/sierra-negra-galapagos\/\" class=\"atgrid__item__top__image\"><img decoding=\"async\" width=\"360\" height=\"240\" src=\"https:\/\/naturegalapagos.com\/es\/wp-content\/uploads\/sites\/3\/2017\/03\/Sierra-Negra-Galapagos-360x240.jpg\" class=\"attachment-thumb_tour_listing_small size-thumb_tour_listing_small wp-post-image\" alt=\"Sierra Negra Galapagos\" srcset=\"https:\/\/naturegalapagos.com\/es\/wp-content\/uploads\/sites\/3\/2017\/03\/Sierra-Negra-Galapagos-360x240.jpg 360w, https:\/\/naturegalapagos.com\/es\/wp-content\/uploads\/sites\/3\/2017\/03\/Sierra-Negra-Galapagos-531x354.jpg 531w, https:\/\/naturegalapagos.com\/es\/wp-content\/uploads\/sites\/3\/2017\/03\/Sierra-Negra-Galapagos-270x180.jpg 270w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/a>\t\t\t\t\t\t\t<div class=\"atgrid__item__angle-wrap\"><div class=\"atgrid__item__angle\" style=\"background-color:#253081\">Compra en Linea! <\/div><\/div>\t\t\t\t\t\t\t<div class=\"atgrid__item__price\"><a href=\"https:\/\/naturegalapagos.com\/es\/tours-en-galapagos\/sierra-negra-galapagos\/\" class=\"atgrid__item__price__button\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#36;<\/span>96<\/bdi><\/span><\/a><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"atgrid__item__icons\"><a href=\"https:\/\/naturegalapagos.com\/es\/tour-category\/ofertas-de-viajes\/\"><i data-toggle=\"tooltip\" title=\"Ofertas de Viajes\" class=\"td-sale-1\"><\/i><\/a><a href=\"https:\/\/naturegalapagos.com\/es\/tour-category\/tours-en-galapagos\/\"><i data-toggle=\"tooltip\" title=\"Tours en Galapagos\" class=\"td-turtle\"><\/i><\/a><\/div>\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"atgrid__item__content\">\n\t\t\t\t\t\t\t<h3 class=\"atgrid__item__title\"><a href=\"https:\/\/naturegalapagos.com\/es\/tours-en-galapagos\/sierra-negra-galapagos\/\">Sierra Negra Galapagos | Tour de Senderismo<\/a><\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"atgrid__item__description\">Sierra Negra Gal\u00e1pagos es un tour de senderismo de un d\u00eda completo! Donde podr\u00e1 admirar la belleza del segundo crater m\u00e1s grande del mundo<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"item-attributes\">\n\t\t\t\t\t\t\t<div class=\"item-attributes__item\"><div class=\"item-attributes__item__content\"><div class=\"item-attributes__item__content__item\"><i class=\"td-backpack\"><\/i><\/div><div class=\"item-attributes__item__content__item item-attributes__item__content__item--text\"><span>Aventura Sencilla<\/span><\/div><\/div><\/div><div class=\"item-attributes__item\"><div class=\"item-attributes__item__content\"><div class=\"item-attributes__item__content__item\"><i class=\"td-calendar-1\"><\/i><\/div><div class=\"item-attributes__item__content__item item-attributes__item__content__item--text\"><span>Todos los D\u00edas<\/span><\/div><\/div><\/div>\t\t\t\t\t\t\t<div class=\"item-attributes__item\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/naturegalapagos.com\/es\/tours-en-galapagos\/sierra-negra-galapagos\/\" class=\"item-attributes__link\"><i class=\"fa fa-long-arrow-right\"><\/i><\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div><!-- .swiper-wrapper -->\n\t\t<\/div><!-- .swiper-container -->\n\t<\/div><!-- .atgrid__slider  -->\n<\/div><!-- .atgrid -->\n[\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;50px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_raw_html css=&#8221;&#8221;]JTNDYnIlMjAlMkYlM0UlMEQlMEElNUJ0cnVzdGluZGV4JTIwbm8tcmVnaXN0cmF0aW9uJTNEdHJpcGFkdmlzb3IlNUQlMjAlM0NiciUyMCUyRiUzRSUwRCUwQSU1QmN1c3RvbV9zaGFycmVfYnV0dG9ucyU1RA==[\/vc_raw_html][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] Explore las maravillas andinas: Emb\u00e1rquese en inolvidables aventuras de trekking con Trek Ecuador Tours Trek Ecuador es una de nuestras secciones mas completas, no solo por los paisajes que visitamos, sino tambi\u00e9n porque nuestros itinerarios que est\u00e1n bien aprovechados en tiempo. Nuestros tours de Senderismo en Ecuador pueden ser de 1 a 4 d\u00edas,<\/p>\n<div class=\"padding-top text-center\"><a href=\"https:\/\/naturegalapagos.com\/es\/tours-en-galapagos\/sierra-negra-galapagos\/\" class=\"atbtn atbtn--medium atbtn--rounded atbtn--transparent\">Leer m\u00e1s<i class=\"atbtn__icon atbtn__icon--right fa fa-long-arrow-right\"><\/i><\/a><\/div>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-4293","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.6 (Yoast SEO v26.1.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trek Ecuador | Itinerarios y precios en un solo lugar<\/title>\n<meta name=\"description\" content=\"Trek Ecuador - Tours de Senderismo por los lugares m\u00e1s hermosos del pa\u00eds. Precios al alcance de tu bolsillo con itinerarios completos. M\u00e1s info clic aqu\u00ed!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/naturegalapagos.com\/es\/trek-ecuador\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trek Ecuador | Itinerarios y precios en un solo lugar\" \/>\n<meta property=\"og:description\" content=\"Trek Ecuador - Tours de Senderismo por los lugares m\u00e1s hermosos del pa\u00eds. Precios al alcance de tu bolsillo con itinerarios completos. M\u00e1s info clic aqu\u00ed!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/naturegalapagos.com\/es\/trek-ecuador\/\" \/>\n<meta property=\"og:site_name\" content=\"Espa\u00f1ol - Nature Galapagos &amp; Ecuador\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/naturegalapagosecuador\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-17T22:08:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/naturegalapagos.com\/es\/wp-content\/uploads\/sites\/3\/2018\/06\/trek-ecuador.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Trek Ecuador | Itinerarios y precios en un solo lugar\" \/>\n<meta name=\"twitter:description\" content=\"Trek Ecuador - Tours de Senderismo por los lugares m\u00e1s hermosos del pa\u00eds. Precios al alcance de tu bolsillo con itinerarios completos. M\u00e1s info clic aqu\u00ed!\" \/>\n<meta name=\"twitter:site\" content=\"@naturegalapagos\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Trek Ecuador | Itinerarios y precios en un solo lugar","description":"Trek Ecuador - Tours de Senderismo por los lugares m\u00e1s hermosos del pa\u00eds. Precios al alcance de tu bolsillo con itinerarios completos. M\u00e1s info clic aqu\u00ed!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/naturegalapagos.com\/es\/trek-ecuador\/","og_locale":"es_ES","og_type":"article","og_title":"Trek Ecuador | Itinerarios y precios en un solo lugar","og_description":"Trek Ecuador - Tours de Senderismo por los lugares m\u00e1s hermosos del pa\u00eds. Precios al alcance de tu bolsillo con itinerarios completos. M\u00e1s info clic aqu\u00ed!","og_url":"https:\/\/naturegalapagos.com\/es\/trek-ecuador\/","og_site_name":"Espa\u00f1ol - Nature Galapagos &amp; Ecuador","article_publisher":"https:\/\/www.facebook.com\/naturegalapagosecuador\/","article_modified_time":"2025-11-17T22:08:52+00:00","og_image":[{"width":1024,"height":512,"url":"https:\/\/naturegalapagos.com\/es\/wp-content\/uploads\/sites\/3\/2018\/06\/trek-ecuador.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Trek Ecuador | Itinerarios y precios en un solo lugar","twitter_description":"Trek Ecuador - Tours de Senderismo por los lugares m\u00e1s hermosos del pa\u00eds. Precios al alcance de tu bolsillo con itinerarios completos. M\u00e1s info clic aqu\u00ed!","twitter_site":"@naturegalapagos","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/naturegalapagos.com\/es\/trek-ecuador\/","url":"https:\/\/naturegalapagos.com\/es\/trek-ecuador\/","name":"Trek Ecuador | Itinerarios y precios en un solo lugar","isPartOf":{"@id":"https:\/\/naturegalapagos.com\/es\/#website"},"datePublished":"2018-06-14T14:16:59+00:00","dateModified":"2025-11-17T22:08:52+00:00","description":"Trek Ecuador - Tours de Senderismo por los lugares m\u00e1s hermosos del pa\u00eds. Precios al alcance de tu bolsillo con itinerarios completos. M\u00e1s info clic aqu\u00ed!","breadcrumb":{"@id":"https:\/\/naturegalapagos.com\/es\/trek-ecuador\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/naturegalapagos.com\/es\/trek-ecuador\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/naturegalapagos.com\/es\/trek-ecuador\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/naturegalapagos.com\/es\/"},{"@type":"ListItem","position":2,"name":"Trek Ecuador"}]},{"@type":"WebSite","@id":"https:\/\/naturegalapagos.com\/es\/#website","url":"https:\/\/naturegalapagos.com\/es\/","name":"Espa\u00f1ol - Nature Galapagos & Ecuador","description":"","publisher":{"@id":"https:\/\/naturegalapagos.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/naturegalapagos.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/naturegalapagos.com\/es\/#organization","name":"Espa\u00f1ol - Nature Galapagos & Ecuador","url":"https:\/\/naturegalapagos.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/naturegalapagos.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/naturegalapagos.com\/es\/wp-content\/uploads\/sites\/3\/2016\/10\/Nature-Galapagos-Logo-COM-300x300.jpg","contentUrl":"https:\/\/naturegalapagos.com\/es\/wp-content\/uploads\/sites\/3\/2016\/10\/Nature-Galapagos-Logo-COM-300x300.jpg","width":300,"height":300,"caption":"Espa\u00f1ol - Nature Galapagos & Ecuador"},"image":{"@id":"https:\/\/naturegalapagos.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/naturegalapagosecuador\/","https:\/\/x.com\/naturegalapagos","https:\/\/www.instagram.com\/naturegalapagos\/","https:\/\/www.pinterest.com\/Naturegalapagos\/","https:\/\/www.youtube.com\/user\/NatureGalapagosTours"]}]}},"_links":{"self":[{"href":"https:\/\/naturegalapagos.com\/es\/wp-json\/wp\/v2\/pages\/4293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/naturegalapagos.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/naturegalapagos.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/naturegalapagos.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/naturegalapagos.com\/es\/wp-json\/wp\/v2\/comments?post=4293"}],"version-history":[{"count":0,"href":"https:\/\/naturegalapagos.com\/es\/wp-json\/wp\/v2\/pages\/4293\/revisions"}],"wp:attachment":[{"href":"https:\/\/naturegalapagos.com\/es\/wp-json\/wp\/v2\/media?parent=4293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}